{"id":1952,"date":"2017-02-10T10:35:14","date_gmt":"2017-02-10T10:35:14","guid":{"rendered":"https:\/\/www.esmadrid.com\/mcb\/?p=1952"},"modified":"2024-06-11T11:29:12","modified_gmt":"2024-06-11T11:29:12","slug":"madrid-arte-arco-madrid","status":"publish","type":"post","link":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/","title":{"rendered":"Madrid es arte: ARCO MADRID"},"content":{"rendered":"<p>Entre el 22 y el 26 de febrero, Madrid se convierte en la capital mundial del arte contempor\u00e1neo con la celebraci\u00f3n de su gran feria anual, que alcanza su 36\u00aa edici\u00f3n.<\/p>\n<p>La Feria Internacional de Arte Contempor\u00e1neo de Madrid arranca esta nueva edici\u00f3n con un objetivo claro: consolidarse como feria de descubrimiento de nuevos talentos y contenidos para coleccionistas y profesionales. Para ello cuenta con un Programa General, en el que participan 160 galer\u00edas, a las que hay que sumar las participantes en el resto de secciones comisariadas: Argentina Plataforma ARCO, con doce, Di\u00e1logos, con otras doce y Opening, con 16. La mayor parte de ellas presentar\u00e1 proyectos enfocados a la presentaci\u00f3n de uno o dos artistas de distintos entornos, reforzando a ARCOmadrid como espacio para el conocimiento de la obra de autores de distintas generaciones.<\/p>\n<p>La participaci\u00f3n de Argentina como pa\u00eds invitado viene a consolidar este a\u00f1o la proyecci\u00f3n de la feria como gran referente latinoamericano en Europa. En este contexto, tambi\u00e9n Madrid se volcar\u00e1 en mostrar su mejor acento latino con diferentes muestras que tendr\u00e1n lugar en los principales centros de arte y museos de la ciudad. As\u00ed podr\u00e1n visitarse las exposiciones sobre la colecci\u00f3n Isabel y Agust\u00edn Coppel, en la Fundaci\u00f3n Banco Santander, la colecci\u00f3n Hochschild, en la sala Alcal\u00e1 31, la colecci\u00f3n Costantini, en la Real Academia de Bellas Artes de San Fernando, y las dedicadas a Diego Bianchi y Luis Garay en Matadero Madrid y Leandro Erlich, en el Espacio Fundaci\u00f3n Telef\u00f3nica, entre otras.<\/p>\n<p>A la alta fidelizaci\u00f3n de las galer\u00edas que forman parte este a\u00f1o en ARCOmadrid hay que a\u00f1adir la presencia de otras nuevas as\u00ed como de pa\u00edses emergentes, que sirven para dibujar los rasgos que perfilan una edici\u00f3n coherente y de calidad. Entre los participantes destacan Alexander and Bonin, Chantal Crousel, Jan Mot\/Sprueth Magers, Lisson Gallery y Team Gallery, adem\u00e1s de otras importantes que mantienen su inter\u00e9s por la feria como Carlier Gebauer, Esther Shipper, Jocelyn Wolff y Kow, y algunas incorporaciones como Dvir, Jablonka Maruani Mercier Gallery, Labor, Michel Rein, Nara Roesler, Supportico Lopez y Tanya Bonakdar.<\/p>\n<p>ARCOmadrid sigue apostando por la presentaci\u00f3n de proyectos de artistas individuales o en di\u00e1logo; di\u00e1logos intergeneracionales a lo largo de toda la feria que contemplan desde los m\u00e1s j\u00f3venes como Elena Alonso y Fito Conesa, hasta artistas que son un referente de nuestro presente como Anna Oppermann, Henri Chopin, Mihai Olos o Robert Breer. La feria vuelve a dar cabida este a\u00f1o a la propuesta SOLO\/DUO. De las galer\u00edas seleccionadas, m\u00e1s de 20 dedicar\u00e1n su estand a uno o dos artistas entre los que se encuentran Alan Charlton, Edgardo Antonio Vigo, Ignasi Aball\u00ed, Jos\u00e9 Mar\u00eda Sicilia o Tom\u00e1s Saraceno. Por su parte, Argentina Plataforma ARCO presentar\u00e1 artistas reconocidos internacionalmente como Alberto Greco, Eduardo Stupia y Mirtha Dermisache, junto a otros a descubrir por el p\u00fablico como Diego Bianchi, Pablo Accinelli o Sol Pipkin. El programa Di\u00e1logos contar\u00e1 con las galer\u00edas seleccionadas por Mar\u00eda de Corral, Lorena Mart\u00ednez de Corral y Catalina Lozano cuyos estands generar\u00e1n contenidos nuevos a la vez que servir\u00e1n para presentar la obra de sus artistas en profundidad. Entre estos, Diango Hern\u00e1ndez y Roman Ondak, as\u00ed como los argentinos Eduardo Navarro, Irene Kopelman y Tom\u00e1s Saraceno. Finalmente, Opening volver\u00e1 a centrarse en galer\u00edas con una trayectoria de un m\u00e1ximo de siete a\u00f1os con el objetivo de aportar nueva informaci\u00f3n y experiencias est\u00e9ticas. Entre los artistas que integran la secci\u00f3n destacan Carme Nogueira, Felipe Cohen y Luis L\u00e1zaro Matos.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre el 22 y el 26 de febrero, Madrid se convierte en la capital mundial del arte contempor\u00e1neo con la celebraci\u00f3n de su gran feria anual, que alcanza su 36\u00aa edici\u00f3n. La Feria Internacional de Arte Contempor\u00e1neo de Madrid arranca esta nueva edici\u00f3n con un objetivo claro: consolidarse como feria de descubrimiento de nuevos talentos [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1972,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1952","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madrid es arte: ARCO MADRID - Madrid Convention Bureau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madrid es arte: ARCO MADRID - Madrid Convention Bureau\" \/>\n<meta property=\"og:description\" content=\"Entre el 22 y el 26 de febrero, Madrid se convierte en la capital mundial del arte contempor\u00e1neo con la celebraci\u00f3n de su gran feria anual, que alcanza su 36\u00aa edici\u00f3n. La Feria Internacional de Arte Contempor\u00e1neo de Madrid arranca esta nueva edici\u00f3n con un objetivo claro: consolidarse como feria de descubrimiento de nuevos talentos [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/\" \/>\n<meta property=\"og:site_name\" content=\"Madrid Convention Bureau\" \/>\n<meta property=\"article:published_time\" content=\"2017-02-10T10:35:14+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T11:29:12+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2017\/02\/arco-WP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"325\" \/>\n\t<meta property=\"og:image:height\" content=\"217\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"headline\":\"Madrid es arte: ARCO MADRID\",\"datePublished\":\"2017-02-10T10:35:14+00:00\",\"dateModified\":\"2024-06-11T11:29:12+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/\"},\"wordCount\":634,\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/arco-WP.jpg\",\"articleSection\":[\"Novedades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/\",\"name\":\"Madrid es arte: ARCO MADRID - Madrid Convention Bureau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/arco-WP.jpg\",\"datePublished\":\"2017-02-10T10:35:14+00:00\",\"dateModified\":\"2024-06-11T11:29:12+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/arco-WP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2017\\\/02\\\/arco-WP.jpg\",\"width\":325,\"height\":217},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-arte-arco-madrid\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madrid es arte: ARCO MADRID\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\",\"name\":\"Madrid Convention Bureau\",\"description\":\"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\",\"name\":\"editor\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madrid es arte: ARCO MADRID - Madrid Convention Bureau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/","og_locale":"es_ES","og_type":"article","og_title":"Madrid es arte: ARCO MADRID - Madrid Convention Bureau","og_description":"Entre el 22 y el 26 de febrero, Madrid se convierte en la capital mundial del arte contempor\u00e1neo con la celebraci\u00f3n de su gran feria anual, que alcanza su 36\u00aa edici\u00f3n. La Feria Internacional de Arte Contempor\u00e1neo de Madrid arranca esta nueva edici\u00f3n con un objetivo claro: consolidarse como feria de descubrimiento de nuevos talentos [&hellip;]","og_url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/","og_site_name":"Madrid Convention Bureau","article_published_time":"2017-02-10T10:35:14+00:00","article_modified_time":"2024-06-11T11:29:12+00:00","og_image":[{"width":325,"height":217,"url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2017\/02\/arco-WP.jpg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/#article","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/"},"author":{"name":"editor","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"headline":"Madrid es arte: ARCO MADRID","datePublished":"2017-02-10T10:35:14+00:00","dateModified":"2024-06-11T11:29:12+00:00","mainEntityOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/"},"wordCount":634,"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2017\/02\/arco-WP.jpg","articleSection":["Novedades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/","url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/","name":"Madrid es arte: ARCO MADRID - Madrid Convention Bureau","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/#primaryimage"},"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2017\/02\/arco-WP.jpg","datePublished":"2017-02-10T10:35:14+00:00","dateModified":"2024-06-11T11:29:12+00:00","author":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"breadcrumb":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/#primaryimage","url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2017\/02\/arco-WP.jpg","contentUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2017\/02\/arco-WP.jpg","width":325,"height":217},{"@type":"BreadcrumbList","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-arte-arco-madrid\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.esmadrid.com\/mcb\/"},{"@type":"ListItem","position":2,"name":"Madrid es arte: ARCO MADRID"}]},{"@type":"WebSite","@id":"https:\/\/www.esmadrid.com\/mcb\/#website","url":"https:\/\/www.esmadrid.com\/mcb\/","name":"Madrid Convention Bureau","description":"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esmadrid.com\/mcb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b","name":"editor","url":"https:\/\/www.esmadrid.com\/mcb\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1952","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/comments?post=1952"}],"version-history":[{"count":1,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1952\/revisions"}],"predecessor-version":[{"id":1953,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1952\/revisions\/1953"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media\/1972"}],"wp:attachment":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media?parent=1952"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/categories?post=1952"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/tags?post=1952"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}