{"id":1677,"date":"2016-09-21T11:15:33","date_gmt":"2016-09-21T11:15:33","guid":{"rendered":"http:\/\/www.esmadrid.com\/mcb\/?p=1677"},"modified":"2024-06-11T11:29:14","modified_gmt":"2024-06-11T11:29:14","slug":"madrid-recoge-testigo-del-world-pride-2017","status":"publish","type":"post","link":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/","title":{"rendered":"Madrid recoge el testigo del World Pride 2017"},"content":{"rendered":"<p>La alcaldesa de Madrid, Manuela Carmena, recibi\u00f3, durante la celebraci\u00f3n del Orgullo Gay 2016 en el sal\u00f3n de actos del Ayuntamiento a la Delegaci\u00f3n Organizadora del Word Pride Madrid 2017, compuesta por los copresidentes de Interpride -la asociaci\u00f3n mundial de organizadores de Orgullos LGBTI-, Brett Hayhoe y Sue Doster, el coordinador general del Orgullo Mundial 2017, Juan Carlos Alonso \u201cChair\u201d y la directora general de Igualdad entre Mujeres y Hombres, Ana Bu\u00f1uel.<\/p>\n<p>El World Pride Madrid 2017 y el Europride 2017 se celebrar\u00e1n del 23 de junio al 2 de julio y su acto central ser\u00e1 la manifestaci\u00f3n Mundial del Orgullo LGTB.<\/p>\n<p>Carmena ha se\u00f1alado: \u201cMadrid fue una de las primeras ciudades en el mundo que dio pasos para hacer posible esa necesidad del reconocimiento de la identidad sexual, que cuando no se reconoce hace sufrir tanto a la humanidad. Por eso, os acogemos con los brazos abiertos y os aseguramos que ser\u00e1 un d\u00eda mundial de la celebraci\u00f3n del orgullo gay absolutamente inolvidable.\u201d<\/p>\n<p>Juan Carlos Alonso, coordinador general del Orgullo Mundial de 2017, ha explicado: \u201cEl Orgullo de Madrid ha transformado nuestra ciudad en un lugar diferente lleno de libertad, igualdad, celebraci\u00f3n, y mucho m\u00e1s que eso. A trav\u00e9s del Word Pride de Madrid queremos compartir con toda la comunidad internacional ese esp\u00edritu de Madrid.\u201d<\/p>\n<p>El World Pride es un evento de Interpride, la asociaci\u00f3n mundial de organizadores de Orgullos LGBTI, cuya misi\u00f3n es empoderar a los diferentes organizadores de\u00a0<em>prides<\/em>\u00a0alrededor del mundo para promover los valores de una sociedad igualitaria. Este evento se ha celebrado en las ciudades de Roma (2000), Jerusal\u00e9n (2006), Londres (2012) y Toronto (2014).<\/p>\n<p>El objetivo de Interpride y de este evento es la promoci\u00f3n de los derechos y la visibilidad del colectivo LGBTI. La celebraci\u00f3n del World Pride requiere el compromiso de los organizadores en distintos \u00e1mbitos como actividades de promoci\u00f3n de los derechos humanos y la visibilidad de organizaciones y colectivos LGBTI durante el World Pride, la organizaci\u00f3n de actividades inclusivas para distintas formas y sensibilidades del colectivo LGBTI as\u00ed como la promoci\u00f3n del World Pride a nivel internacional.<\/p>\n<p>Durante la celebraci\u00f3n del Orgullo de este a\u00f1o, una delegaci\u00f3n de Interpride \u00a0visitar\u00e1 Madrid para inspeccionar los diferentes espacios en los que se desarrollar\u00e1 el programa de 2017, as\u00ed como los diferentes eventos que se tienen lugar durante esta edici\u00f3n, considerada como un gran ensayo general de cara al a\u00f1o pr\u00f3ximo. Las zonas de la ciudad que visitar\u00e1n son los jardines de Cecilio Rodr\u00edguez, CentroCentro, Matadero, Madrid R\u00edo y diversos escenarios y localizaciones de la programaci\u00f3n del Orgullo de este a\u00f1o.<\/p>\n<p><strong>40 a\u00f1os de marchas LGTBI<\/strong><\/p>\n<p>La candidatura de Madrid para el World Pride de 2017 se consigui\u00f3 en el a\u00f1o 2012 y \u00a0se centra en el reconocimiento del movimiento LGBTI en Espa\u00f1a y Madrid. En ese a\u00f1o se celebrar\u00e1n 40 a\u00f1os de las primeras marchas del colectivo LGBTI; 30 a\u00f1os de los primeros Orgullos en el barrio de Chueca; 20 a\u00f1os de las primeras carrozas en la manifestaci\u00f3n del Orgullo de Madrid y 10 a\u00f1os de la celebraci\u00f3n del Europride, que coloc\u00f3 a Madrid como una de las capitales LGBTI de Europa.\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La alcaldesa de Madrid, Manuela Carmena, recibi\u00f3, durante la celebraci\u00f3n del Orgullo Gay 2016 en el sal\u00f3n de actos del Ayuntamiento a la Delegaci\u00f3n Organizadora del Word Pride Madrid 2017, compuesta por los copresidentes de Interpride -la asociaci\u00f3n mundial de organizadores de Orgullos LGBTI-, Brett Hayhoe y Sue Doster, el coordinador general del Orgullo Mundial [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1703,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1677","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Madrid recoge el testigo del World Pride 2017 - Madrid Convention Bureau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Madrid recoge el testigo del World Pride 2017 - Madrid Convention Bureau\" \/>\n<meta property=\"og:description\" content=\"La alcaldesa de Madrid, Manuela Carmena, recibi\u00f3, durante la celebraci\u00f3n del Orgullo Gay 2016 en el sal\u00f3n de actos del Ayuntamiento a la Delegaci\u00f3n Organizadora del Word Pride Madrid 2017, compuesta por los copresidentes de Interpride -la asociaci\u00f3n mundial de organizadores de Orgullos LGBTI-, Brett Hayhoe y Sue Doster, el coordinador general del Orgullo Mundial [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"Madrid Convention Bureau\" \/>\n<meta property=\"article:published_time\" content=\"2016-09-21T11:15:33+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T11:29:14+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/09\/MADO-2016-WP.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"293\" \/>\n\t<meta property=\"og:image:height\" content=\"200\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"headline\":\"Madrid recoge el testigo del World Pride 2017\",\"datePublished\":\"2016-09-21T11:15:33+00:00\",\"dateModified\":\"2024-06-11T11:29:14+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/\"},\"wordCount\":552,\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/MADO-2016-WP.jpg\",\"articleSection\":[\"Novedades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/\",\"name\":\"Madrid recoge el testigo del World Pride 2017 - Madrid Convention Bureau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/MADO-2016-WP.jpg\",\"datePublished\":\"2016-09-21T11:15:33+00:00\",\"dateModified\":\"2024-06-11T11:29:14+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/MADO-2016-WP.jpg\",\"contentUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/09\\\/MADO-2016-WP.jpg\",\"width\":293,\"height\":200},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/madrid-recoge-testigo-del-world-pride-2017\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Madrid recoge el testigo del World Pride 2017\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\",\"name\":\"Madrid Convention Bureau\",\"description\":\"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\",\"name\":\"editor\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Madrid recoge el testigo del World Pride 2017 - Madrid Convention Bureau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/","og_locale":"es_ES","og_type":"article","og_title":"Madrid recoge el testigo del World Pride 2017 - Madrid Convention Bureau","og_description":"La alcaldesa de Madrid, Manuela Carmena, recibi\u00f3, durante la celebraci\u00f3n del Orgullo Gay 2016 en el sal\u00f3n de actos del Ayuntamiento a la Delegaci\u00f3n Organizadora del Word Pride Madrid 2017, compuesta por los copresidentes de Interpride -la asociaci\u00f3n mundial de organizadores de Orgullos LGBTI-, Brett Hayhoe y Sue Doster, el coordinador general del Orgullo Mundial [&hellip;]","og_url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/","og_site_name":"Madrid Convention Bureau","article_published_time":"2016-09-21T11:15:33+00:00","article_modified_time":"2024-06-11T11:29:14+00:00","og_image":[{"width":293,"height":200,"url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/09\/MADO-2016-WP.jpg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/#article","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/"},"author":{"name":"editor","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"headline":"Madrid recoge el testigo del World Pride 2017","datePublished":"2016-09-21T11:15:33+00:00","dateModified":"2024-06-11T11:29:14+00:00","mainEntityOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/"},"wordCount":552,"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/09\/MADO-2016-WP.jpg","articleSection":["Novedades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/","url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/","name":"Madrid recoge el testigo del World Pride 2017 - Madrid Convention Bureau","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/#primaryimage"},"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/09\/MADO-2016-WP.jpg","datePublished":"2016-09-21T11:15:33+00:00","dateModified":"2024-06-11T11:29:14+00:00","author":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"breadcrumb":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/#primaryimage","url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/09\/MADO-2016-WP.jpg","contentUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/09\/MADO-2016-WP.jpg","width":293,"height":200},{"@type":"BreadcrumbList","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/madrid-recoge-testigo-del-world-pride-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.esmadrid.com\/mcb\/"},{"@type":"ListItem","position":2,"name":"Madrid recoge el testigo del World Pride 2017"}]},{"@type":"WebSite","@id":"https:\/\/www.esmadrid.com\/mcb\/#website","url":"https:\/\/www.esmadrid.com\/mcb\/","name":"Madrid Convention Bureau","description":"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esmadrid.com\/mcb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b","name":"editor","url":"https:\/\/www.esmadrid.com\/mcb\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/comments?post=1677"}],"version-history":[{"count":2,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1677\/revisions"}],"predecessor-version":[{"id":1709,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1677\/revisions\/1709"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media\/1703"}],"wp:attachment":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media?parent=1677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/categories?post=1677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/tags?post=1677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}