{"id":1577,"date":"2016-06-15T15:01:01","date_gmt":"2016-06-15T15:01:01","guid":{"rendered":"http:\/\/www.esmadrid.com\/mcb\/?p=1577"},"modified":"2024-06-11T11:29:15","modified_gmt":"2024-06-11T11:29:15","slug":"mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event","status":"publish","type":"post","link":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/","title":{"rendered":"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event"},"content":{"rendered":"<p>Madrid Convention Bureau (MCB), dependiente del \u00c1rea de Turismo de Madrid Destino (Ayuntamiento de Madrid), organiz\u00f3 anoche un encuentro con sus empresas asociadas. Casi 200 personas asistieron a esta reuni\u00f3n de <i><em style=\"font-weight: inherit\">networking<\/em><\/i> en el Teatro Goya, una de las sedes asociadas a MCB.<\/p>\n<p>Este evento, cuya primera edici\u00f3n fue en 2009, ya se ha consolidado como un punto de encuentro en el que las empresas asociadas pueden intercambiar opiniones sobre la profesi\u00f3n. De esta manera, MCB consigue favorecer sinergias y potenciar la participaci\u00f3n activa de todos los asociados.<\/p>\n<p><span style=\"font-style: inherit;font-weight: inherit\">El objetivo de esta nueva edici\u00f3n de <\/span><i><em style=\"font-weight: inherit\">Networking Event <\/em><\/i><span style=\"font-style: inherit;font-weight: inherit\">era que todas las empresas asociadas se interrelacionaran y conocieran de forma directa el m\u00e9todo de trabajo y promoci\u00f3n de MCB en los mercados emisores.<\/span><\/p>\n<p><strong style=\"font-weight: 700 !important;font-style: inherit\">Captaci\u00f3n de grandes eventos<\/strong><\/p>\n<p>Primero en Londres y Chicago en 2015, y en Hamburgo y M\u00fcnich este a\u00f1o, MCB ha puesto en marcha presentaciones innovadoras en las que la experiencia prima sobre el conocimiento te\u00f3rico y los asistentes pasan de ser meros espectadores a ser part\u00edcipes en actividades l\u00fadicas aplicadas a las acciones de promoci\u00f3n de destino.<\/p>\n<p>En el caso del <i><em style=\"font-weight: inherit\">Networking Event<\/em><\/i> que tuvo lugar anoche, todas las actividades giraron en torno a dos s\u00edmbolos bien conocidos de la ciudad de Madrid: Las Meninas y el \u201cgato\u201d.<\/p>\n<p>El resultado de estas presentaciones es que los asistentes aprenden de forma experiencial y divertida atributos y cualidades positivas del destino que, a la larga, perduran en el recuerdo con mayor intensidad que cualquier dato estad\u00edstico. Este tipo de actividades permite no s\u00f3lo que los participantes se diviertan, sino que haya una interacci\u00f3n muy elevada entre todos los asistentes, imposible de conseguir con otros formatos.<\/p>\n<p>MCB ha recibido una respuesta muy positiva en todas las presentaciones realizadas hasta el momento, en las que los asistentes han expresado un alto grado de satisfacci\u00f3n. Con este nuevo formato MCB est\u00e1 a la cabeza del uso herramientas para la captaci\u00f3n de grandes eventos.\/<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Madrid Convention Bureau (MCB), dependiente del \u00c1rea de Turismo de Madrid Destino (Ayuntamiento de Madrid), organiz\u00f3 anoche un encuentro con sus empresas asociadas. Casi 200 personas asistieron a esta reuni\u00f3n de networking en el Teatro Goya, una de las sedes asociadas a MCB. Este evento, cuya primera edici\u00f3n fue en 2009, ya se ha consolidado [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1578,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1577","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event - Madrid Convention Bureau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event - Madrid Convention Bureau\" \/>\n<meta property=\"og:description\" content=\"Madrid Convention Bureau (MCB), dependiente del \u00c1rea de Turismo de Madrid Destino (Ayuntamiento de Madrid), organiz\u00f3 anoche un encuentro con sus empresas asociadas. Casi 200 personas asistieron a esta reuni\u00f3n de networking en el Teatro Goya, una de las sedes asociadas a MCB. Este evento, cuya primera edici\u00f3n fue en 2009, ya se ha consolidado [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/\" \/>\n<meta property=\"og:site_name\" content=\"Madrid Convention Bureau\" \/>\n<meta property=\"article:published_time\" content=\"2016-06-15T15:01:01+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T11:29:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/06\/MADRID_CONVENTION_BUREAU-200.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"960\" \/>\n\t<meta property=\"og:image:height\" content=\"640\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"headline\":\"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event\",\"datePublished\":\"2016-06-15T15:01:01+00:00\",\"dateModified\":\"2024-06-11T11:29:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/\"},\"wordCount\":351,\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/MADRID_CONVENTION_BUREAU-200.jpg\",\"articleSection\":[\"Novedades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/\",\"name\":\"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event - Madrid Convention Bureau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/MADRID_CONVENTION_BUREAU-200.jpg\",\"datePublished\":\"2016-06-15T15:01:01+00:00\",\"dateModified\":\"2024-06-11T11:29:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/MADRID_CONVENTION_BUREAU-200.jpg\",\"contentUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/06\\\/MADRID_CONVENTION_BUREAU-200.jpg\",\"width\":960,\"height\":640},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\",\"name\":\"Madrid Convention Bureau\",\"description\":\"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\",\"name\":\"editor\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event - Madrid Convention Bureau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/","og_locale":"es_ES","og_type":"article","og_title":"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event - Madrid Convention Bureau","og_description":"Madrid Convention Bureau (MCB), dependiente del \u00c1rea de Turismo de Madrid Destino (Ayuntamiento de Madrid), organiz\u00f3 anoche un encuentro con sus empresas asociadas. Casi 200 personas asistieron a esta reuni\u00f3n de networking en el Teatro Goya, una de las sedes asociadas a MCB. Este evento, cuya primera edici\u00f3n fue en 2009, ya se ha consolidado [&hellip;]","og_url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/","og_site_name":"Madrid Convention Bureau","article_published_time":"2016-06-15T15:01:01+00:00","article_modified_time":"2024-06-11T11:29:15+00:00","og_image":[{"width":960,"height":640,"url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/06\/MADRID_CONVENTION_BUREAU-200.jpg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"2 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/#article","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/"},"author":{"name":"editor","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"headline":"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event","datePublished":"2016-06-15T15:01:01+00:00","dateModified":"2024-06-11T11:29:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/"},"wordCount":351,"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/06\/MADRID_CONVENTION_BUREAU-200.jpg","articleSection":["Novedades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/","url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/","name":"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event - Madrid Convention Bureau","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/#primaryimage"},"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/06\/MADRID_CONVENTION_BUREAU-200.jpg","datePublished":"2016-06-15T15:01:01+00:00","dateModified":"2024-06-11T11:29:15+00:00","author":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"breadcrumb":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/#primaryimage","url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/06\/MADRID_CONVENTION_BUREAU-200.jpg","contentUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/06\/MADRID_CONVENTION_BUREAU-200.jpg","width":960,"height":640},{"@type":"BreadcrumbList","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mcb-reunio-empresas-asociadas-la-novena-edicion-del-networking-event\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.esmadrid.com\/mcb\/"},{"@type":"ListItem","position":2,"name":"MCB reuni\u00f3 a sus empresas asociadas en la novena edici\u00f3n del Networking Event"}]},{"@type":"WebSite","@id":"https:\/\/www.esmadrid.com\/mcb\/#website","url":"https:\/\/www.esmadrid.com\/mcb\/","name":"Madrid Convention Bureau","description":"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esmadrid.com\/mcb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b","name":"editor","url":"https:\/\/www.esmadrid.com\/mcb\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1577","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/comments?post=1577"}],"version-history":[{"count":2,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1577\/revisions"}],"predecessor-version":[{"id":1580,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1577\/revisions\/1580"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media\/1578"}],"wp:attachment":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media?parent=1577"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/categories?post=1577"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/tags?post=1577"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}