{"id":1495,"date":"2016-04-30T07:51:45","date_gmt":"2016-04-30T07:51:45","guid":{"rendered":"http:\/\/www.esmadrid.com\/mcb\/?p=1495"},"modified":"2024-06-11T11:29:15","modified_gmt":"2024-06-11T11:29:15","slug":"mercado-moncloa-se-posiciona-sede-la-organizacion-eventos","status":"publish","type":"post","link":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/","title":{"rendered":"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos"},"content":{"rendered":"<p>Adem\u00e1s de hacer la compra diaria, el espacio ofrece ahora sus <strong><span style=\"color: #3366ff\">tres plantas y sus 700m2 como venue cultural y gastron\u00f3mica<\/span><\/strong>. El mercado cuenta con un restaurante de 170m2 donde se pueden celebrar c\u00f3cteles para 200 personas o banquetes para 120 asistentes.<\/p>\n<p>En la planta calle se encuentra el kiosko con nueve puestos de comida diferentes y personalizables del mercado: sushi, hamburguesas de vacuno, embutidos, pasteler\u00eda y hasta un puesto italiano con pasta fresca.<\/p>\n<p>Un total de 186m2 donde se puede contar con cuatro <strong><span style=\"color: #3366ff\">pantallas led para personalizar el evento<\/span><\/strong> al igual que la cristalera de la fachada que puede integrar los motivos corporativos que se necesiten. Por \u00faltimo, en la primera planta, de 254m2, se encuentra una zona gastron\u00f3mica unida a un espacio di\u00e1fano donde poder realizar presentaciones, reuniones o cenas privadas.<\/p>\n<p>M\u00e1s informaci\u00f3n: <a href=\"http:\/\/mercadomoncloa.es\/\">http:\/\/mercadomoncloa.es\/ <\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Adem\u00e1s de hacer la compra diaria, el espacio ofrece ahora sus tres plantas y sus 700m2 como venue cultural y gastron\u00f3mica. El mercado cuenta con un restaurante de 170m2 donde se pueden celebrar c\u00f3cteles para 200 personas o banquetes para 120 asistentes. En la planta calle se encuentra el kiosko con nueve puestos de comida [&hellip;]<\/p>\n","protected":false},"author":2,"featured_media":1497,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[1],"tags":[],"class_list":["post-1495","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-novedades"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos - Madrid Convention Bureau<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos - Madrid Convention Bureau\" \/>\n<meta property=\"og:description\" content=\"Adem\u00e1s de hacer la compra diaria, el espacio ofrece ahora sus tres plantas y sus 700m2 como venue cultural y gastron\u00f3mica. El mercado cuenta con un restaurante de 170m2 donde se pueden celebrar c\u00f3cteles para 200 personas o banquetes para 120 asistentes. En la planta calle se encuentra el kiosko con nueve puestos de comida [&hellip;]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/\" \/>\n<meta property=\"og:site_name\" content=\"Madrid Convention Bureau\" \/>\n<meta property=\"article:published_time\" content=\"2016-04-30T07:51:45+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-06-11T11:29:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/05\/moncloa2_1412266249.165.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"660\" \/>\n\t<meta property=\"og:image:height\" content=\"335\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"editor\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Escrito por\" \/>\n\t<meta name=\"twitter:data1\" content=\"editor\" \/>\n\t<meta name=\"twitter:label2\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minuto\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/\"},\"author\":{\"name\":\"editor\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"headline\":\"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos\",\"datePublished\":\"2016-04-30T07:51:45+00:00\",\"dateModified\":\"2024-06-11T11:29:15+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/\"},\"wordCount\":158,\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/moncloa2_1412266249.165.jpg\",\"articleSection\":[\"Novedades\"],\"inLanguage\":\"es\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/\",\"name\":\"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos - Madrid Convention Bureau\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/moncloa2_1412266249.165.jpg\",\"datePublished\":\"2016-04-30T07:51:45+00:00\",\"dateModified\":\"2024-06-11T11:29:15+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/moncloa2_1412266249.165.jpg\",\"contentUrl\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/wp-content\\\/uploads\\\/2016\\\/05\\\/moncloa2_1412266249.165.jpg\",\"width\":660,\"height\":335},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/novedades\\\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#website\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/\",\"name\":\"Madrid Convention Bureau\",\"description\":\"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/#\\\/schema\\\/person\\\/cc0f4a72833d0376034828bc8f99ca0b\",\"name\":\"editor\",\"url\":\"https:\\\/\\\/www.esmadrid.com\\\/mcb\\\/author\\\/editor\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos - Madrid Convention Bureau","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/","og_locale":"es_ES","og_type":"article","og_title":"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos - Madrid Convention Bureau","og_description":"Adem\u00e1s de hacer la compra diaria, el espacio ofrece ahora sus tres plantas y sus 700m2 como venue cultural y gastron\u00f3mica. El mercado cuenta con un restaurante de 170m2 donde se pueden celebrar c\u00f3cteles para 200 personas o banquetes para 120 asistentes. En la planta calle se encuentra el kiosko con nueve puestos de comida [&hellip;]","og_url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/","og_site_name":"Madrid Convention Bureau","article_published_time":"2016-04-30T07:51:45+00:00","article_modified_time":"2024-06-11T11:29:15+00:00","og_image":[{"width":660,"height":335,"url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/05\/moncloa2_1412266249.165.jpg","type":"image\/jpeg"}],"author":"editor","twitter_card":"summary_large_image","twitter_misc":{"Escrito por":"editor","Tiempo de lectura":"1 minuto"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/#article","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/"},"author":{"name":"editor","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"headline":"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos","datePublished":"2016-04-30T07:51:45+00:00","dateModified":"2024-06-11T11:29:15+00:00","mainEntityOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/"},"wordCount":158,"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/05\/moncloa2_1412266249.165.jpg","articleSection":["Novedades"],"inLanguage":"es"},{"@type":"WebPage","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/","url":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/","name":"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos - Madrid Convention Bureau","isPartOf":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/#primaryimage"},"image":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/#primaryimage"},"thumbnailUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/05\/moncloa2_1412266249.165.jpg","datePublished":"2016-04-30T07:51:45+00:00","dateModified":"2024-06-11T11:29:15+00:00","author":{"@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b"},"breadcrumb":{"@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/#primaryimage","url":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/05\/moncloa2_1412266249.165.jpg","contentUrl":"https:\/\/www.esmadrid.com\/mcb\/wp-content\/uploads\/2016\/05\/moncloa2_1412266249.165.jpg","width":660,"height":335},{"@type":"BreadcrumbList","@id":"https:\/\/www.esmadrid.com\/mcb\/novedades\/mercado-moncloa-se-posiciona-sede-la-organizacion-eventos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.esmadrid.com\/mcb\/"},{"@type":"ListItem","position":2,"name":"El mercado de Moncloa se posiciona como sede para la organizaci\u00f3n de eventos"}]},{"@type":"WebSite","@id":"https:\/\/www.esmadrid.com\/mcb\/#website","url":"https:\/\/www.esmadrid.com\/mcb\/","name":"Madrid Convention Bureau","description":"Madrid Convention Bureau cuenta con un Equipo de profesionales que le asesorar\u00e1 sobre los mejores espacios y proveedores de servicios del sector MICE","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.esmadrid.com\/mcb\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Person","@id":"https:\/\/www.esmadrid.com\/mcb\/#\/schema\/person\/cc0f4a72833d0376034828bc8f99ca0b","name":"editor","url":"https:\/\/www.esmadrid.com\/mcb\/author\/editor\/"}]}},"_links":{"self":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1495","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/comments?post=1495"}],"version-history":[{"count":6,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1495\/revisions"}],"predecessor-version":[{"id":1514,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/posts\/1495\/revisions\/1514"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media\/1497"}],"wp:attachment":[{"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/media?parent=1495"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/categories?post=1495"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.esmadrid.com\/mcb\/wp-json\/wp\/v2\/tags?post=1495"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}